{"id":16134,"date":"2024-12-30T14:53:55","date_gmt":"2024-12-30T14:53:55","guid":{"rendered":"https:\/\/motos-motor.com.br\/fipet\/preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2007"},"modified":"2026-05-06T18:51:02","modified_gmt":"2026-05-06T18:51:02","slug":"preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2007","status":"publish","type":"post","link":"https:\/\/motos-motor.com.br\/fipet\/preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2007\/","title":{"rendered":"Tabela Fipe MERCEDES-BENZ Accelo 715C 2p Diesel 2007 pre\u00e7o"},"content":{"rendered":"<p>O pre\u00e7o fipe do modelo MERCEDES-BENZ Accelo 715C 2p Diesel 2007 a diesel \u00e9 de <strong>R$ 138.142<\/strong>, segundo dados da Tabela Fipe. No hist\u00f3rico de pre\u00e7os mais recentes, \u00e9 poss\u00edvel notar que este modelo obteve uma valoriza\u00e7\u00e3o acumulada de 99,60% entre maio de 2021 e maio de 2026: Em maio de 2021 o pre\u00e7o era de R$ 69.211 passando para <span itemprop='price' content='138142'>R$ 138.142<\/span> em maio de 2026. Isso representa um aumento de R$ 68.931. Al\u00e9m disso, \u00e9 relevante observar que esse modelo acumulou 2 varia\u00e7\u00f5es de baixa consecutivas nos \u00faltimos meses. O maior pre\u00e7o nesse per\u00edodo foi de R$ 139.535 em mar\u00e7o de 2026 e o menor pre\u00e7o foi de R$ 69.211 em maio de 2021. Veja mais a seguir.<\/p>\n<ul>\n<li>&#128197; <a href=\"#Historico\">Hist\u00f3rico<\/a><\/li>\n<li>&#128200; <a href=\"#GraficoPrecos\">Gr\u00e1fico de Pre\u00e7os<\/a><\/li>\n<li>&#128201; <a href=\"#GraficoDepreciacao\">Gr\u00e1fico de Deprecia\u00e7\u00f5es<\/a><\/li>\n<\/ul>\n<h2>Tabela MERCEDES-BENZ Accelo 715C 2p Diesel 2007<\/h2>\n<p>Tabela atual com os atributos de identifica\u00e7\u00e3o:<\/p>\n<table border='1' style='border-collapse: collapse; width: 100%;'>\n<thead>\n<tr>\n<th colspan='2' style='text-align: left;'>Identifica\u00e7\u00e3o Fipe<\/th>\n<\/tr>\n<\/thead>\n<tbody style='background-color: rgba(0, 128, 0, 0.1); color: black;'>\n<tr>\n<td>Marca<\/td>\n<td><strong>MERCEDES-BENZ<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Modelo<\/td>\n<td><strong>Accelo 715C 2p (diesel)<strong><\/td>\n<\/tr>\n<tr>\n<td>Ano\/Modelo<\/td>\n<td><strong>2007<\/strong><\/td>\n<\/tr>\n<tr>\n<td>C\u00f3digo Fipe<\/td>\n<td>509224-8<\/td>\n<\/tr>\n<tr>\n<td>Combust\u00edvel<\/td>\n<td>Diesel<\/td>\n<\/tr>\n<tr>\n<td>Pot\u00eancia\/Motor<\/td>\n<td>150 cv*<\/td>\n<\/tr>\n<tr>\n<td>Refer\u00eancia<\/td>\n<td>maio de 2026<\/td>\n<\/tr>\n<tr>\n<td><strong>Pre\u00e7o<\/strong><\/td>\n<td><strong>R$ 138.142<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 id='Historico'>Hist\u00f3rico Fipe<\/h2>\n<p>Confira abaixo a tabela simplificada, que traz os valores mais importantes: pre\u00e7os m\u00ednimo, m\u00e1ximo e o atual no per\u00edodo considerado. As varia\u00e7\u00f5es acumuladas referem-se ao ponto de partida do per\u00edodo (coluna um) e ao menor pre\u00e7o alcan\u00e7ado (coluna dois).<\/p>\n<table border='1' style='border-collapse: collapse; width: 100%;'>\n<th colspan='5' style='text-align: left;'>Hist\u00f3rico de pre\u00e7os com \u00edndices de varia\u00e7\u00e3o<\/th>\n<tr style='background-color: rgba(234, 234, 234, 0.1); color: black;'>\n<th>M\u00eas\/Ano<\/th>\n<th>Pre\u00e7o (R$)<\/th>\n<th>Varia\u00e7\u00e3o Mensal<\/th>\n<th colspan='2'>Varia\u00e7\u00e3o Acumulada<\/th>\n<\/tr>\n<tr style='border: 2px solid #003cff; font-weight: bold;'>\n<td style='background-color: rgba(234, 234, 234, 0.1); color: black;'>05\/2021<\/td>\n<td style='background-color: rgba(234, 234, 234, 0.1); color: black;'>69.211<\/td>\n<td style='background-color: rgba(234, 234, 234, 0.1); color: black;'>0,00%<\/td>\n<td style='background-color: rgba(234, 234, 234, 0.1); color: black;'>0,00%<\/td>\n<td style='background-color: rgba(234, 234, 234, 0.1); color: black;'>0,00%<\/td>\n<\/tr>\n<tr >\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>05\/2022<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>114.415<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>14,35%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>65,31%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>65,31%<\/td>\n<\/tr>\n<tr >\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>05\/2023<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>122.499<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>1,78%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>76,99%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>76,99%<\/td>\n<\/tr>\n<tr >\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>05\/2024<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>119.197<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>0,54%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>72,22%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>72,22%<\/td>\n<\/tr>\n<tr >\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>05\/2025<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>128.189<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>3,12%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>85,21%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>85,21%<\/td>\n<\/tr>\n<tr >\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>09\/2025<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>133.485<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>1,28%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>92,87%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>92,87%<\/td>\n<\/tr>\n<tr >\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>01\/2026<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>133.549<\/td>\n<td style='background-color: rgba(255, 165, 0, 0.1); color: black;'>-0,50%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>92,96%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>92,96%<\/td>\n<\/tr>\n<tr style='border: 2px solid #003cff; font-weight: bold;'>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>03\/2026<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>139.535<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>3,62%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>101,61%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>101,61%<\/td>\n<\/tr>\n<tr >\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>04\/2026<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>138.837<\/td>\n<td style='background-color: rgba(255, 165, 0, 0.1); color: black;'>-0,50%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>100,60%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>100,60%<\/td>\n<\/tr>\n<tr style='border: 2px solid #003cff; font-weight: bold;'>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>05\/2026<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>138.142<\/td>\n<td style='background-color: rgba(255, 165, 0, 0.1); color: black;'>-0,50%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>99,60%<\/td>\n<td style='background-color: rgba(0, 128, 0, 0.1); color: black;'>99,60%<\/td>\n<\/tr>\n<\/table>\n<h2 id='GraficoPrecos'>Gr\u00e1fico de pre\u00e7os MERCEDES-BENZ Accelo 715C 2p (diesel) 2007<\/h2>\n<p>O gr\u00e1fico abaixo mostra a evolu\u00e7\u00e3o dos pre\u00e7os durante o intervalo escolhido, com base nas informa\u00e7\u00f5es fornecidas pela Fipe.<\/p>\n<p><script type=\"text\/javascript\">\n    function loadGoogleCharts(callback) {\n    if (typeof google !== 'undefined' && google.charts) {\n    \/\/ Se a biblioteca j\u00e1 est\u00e1 carregada, chamar o callback diretamente\n    callback();\n    } else {\n    \/\/ Caso contr\u00e1rio, carregar o script\n    if (!document.getElementById('google-charts-script')) {\n    var script = document.createElement('script');\n    script.id = 'google-charts-script';\n    script.src = 'https:\/\/www.gstatic.com\/charts\/loader.js';\n    script.async = true;\n    script.onload = callback;\n    document.head.appendChild(script);\n    } else {\n    \/\/ Se o script j\u00e1 est\u00e1 em processo de carregamento, esperar at\u00e9 que carregue\n    document.getElementById('google-charts-script').addEventListener('load', callback);\n    }\n    }\n    }\n    function drawChart0() {\n    var largura = document.body.clientWidth - 20;\n    if (largura > 615) {\n    largura = 620;\n    }\n    google.charts.load('current', {'packages':['corechart'], 'language': 'pt'});\n    google.charts.setOnLoadCallback(function() {\n    var data = google.visualization.arrayToDataTable([\n    ['M\u00eas\/Ano', 'Accelo 715C 2p (diesel) 2007'],\n    ['05\/2021', 69211.00],\n['02\/2022', 100058.00],\n['11\/2022', 118285.00],\n['08\/2023', 122090.00],\n['05\/2024', 119197.00],\n['02\/2025', 124313.00],\n['07\/2025', 132458.00],\n['10\/2025', 135574.00],\n['01\/2026', 133549.00],\n['03\/2026', 139535.00],\n['04\/2026', 138837.00],\n['05\/2026', 138142.00]\n    ]);\n    var options = {\n    title: 'FIPE MERCEDES-BENZ Accelo 715C 2p (diesel) 2007',\n    titlePosition: 'top',\n    crosshair: { trigger: 'none', orientation: 'horizontal', opacity: 0.8 },\n    legend: { position: 'bottom', maxLines: 1, textStyle: { fontSize: 12 } },\n    chartArea: {width: '100%', height: '100%', left: 5, top: 20, right: 5, bottom: 25},\n    colors: [\"#00f\"],\n    series: {0: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}},\n    explorer: {\n    actions: ['dragToZoom', 'rightClickToReset'],\n    maxZoomIn: .15\n    },\n    hAxis: {\n    textPosition: 'in',\n    title: '',\n    viewWindowMode: 'explicit',\n    format: 'MM\/YYYY',\n    gridlines: {color: '#ebebf5'}\n    },\n    vAxis: {\n    textPosition: 'in',\n    title: '',\n    format: 'short',\n    viewWindowMode: 'explicit',\n    gridlines: {color: '#ebebf5'}\n    },\n    curveType: 'function',\n    width: largura,\n    height: 300,\n    backgroundColor: {stroke: 'blue', fill: '#f6f6fd', strokeWidth: 1}\n    };\n    var chart = new google.visualization.LineChart(document.getElementById('chart_div0'));\n    chart.draw(data, options);\n    });\n    }\n    \/\/ Carregar o script do Google Charts e iniciar o gr\u00e1fico espec\u00edfico\n    loadGoogleCharts(drawChart0);\n    <\/script><\/p>\n<div id=\"chart_div0\" style=\"min-height:300px;\"><\/div>\n<h2 id='GraficoDepreciacao'>Gr\u00e1fico da deprecia\u00e7\u00e3o MERCEDES-BENZ Accelo 715C 2p (diesel) 2007<\/h2>\n<p>O gr\u00e1fico a seguir mostra a evolu\u00e7\u00e3o da cota\u00e7\u00e3o nos \u00faltimos meses (linha azul) em contraste com a m\u00e9dia hist\u00f3rica de modelos semelhantes de mesmo ano (linha laranja), conforme os dados da Fipe. A varia\u00e7\u00e3o da cota\u00e7\u00e3o do d\u00f3lar tamb\u00e9m est\u00e1 presente (linha verde), dividida por 5 para facilitar a interpreta\u00e7\u00e3o.<\/p>\n<p><script type=\"text\/javascript\">\n    function loadGoogleCharts(callback) {\n    if (typeof google !== 'undefined' && google.charts) {\n    \/\/ Se a biblioteca j\u00e1 est\u00e1 carregada, chamar o callback diretamente\n    callback();\n    } else {\n    \/\/ Caso contr\u00e1rio, carregar o script\n    if (!document.getElementById('google-charts-script')) {\n    var script = document.createElement('script');\n    script.id = 'google-charts-script';\n    script.src = 'https:\/\/www.gstatic.com\/charts\/loader.js';\n    script.async = true;\n    script.onload = callback;\n    document.head.appendChild(script);\n    } else {\n    \/\/ Se o script j\u00e1 est\u00e1 em processo de carregamento, esperar at\u00e9 que carregue\n    document.getElementById('google-charts-script').addEventListener('load', callback);\n    }\n    }\n    }\n    function drawChart1() {\n    var largura = document.body.clientWidth - 20;\n    if (largura > 615) {\n    largura = 620;\n    }\n    google.charts.load('current', {'packages':['corechart'], 'language': 'pt'});\n    google.charts.setOnLoadCallback(function() {\n    var data = google.visualization.arrayToDataTable([\n    ['M\u00eas\/Ano', 'Accelo 715C 2p (diesel) 2007', 'Todos 2007', 'D\u00f3lar (\u00f75)'],\n    ['05\/2025', 0.00, 0.00, 0.00],\n['06\/2025', 1.63, 0.01, -0.03],\n['07\/2025', 3.33, -0.01, -0.86],\n['08\/2025', 2.81, 0.14, -0.26],\n['09\/2025', 4.13, -0.34, -0.85],\n['10\/2025', 5.76, -0.58, -1.25],\n['11\/2025', 5.23, -0.92, -1.03],\n['12\/2025', 4.71, -1.06, -1.19],\n['01\/2026', 4.18, -1.27, -0.69],\n['02\/2026', 5.05, -1.47, -1.71],\n['03\/2026', 8.85, -1.45, -1.89],\n['04\/2026', 8.31, -1.91, -1.69],\n['05\/2026', 7.76, -2.29, -2.48]\n    ]);\n    var options = {\n    title: '(%) Varia\u00e7\u00e3o Accelo 715C 2p (diesel) 2007 vs M\u00e9dia Modelos 2007 vs D\u00f3lar',\n    titlePosition: 'top',\n    crosshair: { trigger: 'none', orientation: 'horizontal', opacity: 0.8 },\n    legend: { position: 'bottom', maxLines: 1, textStyle: { fontSize: 12 } },\n    chartArea: {width: '100%', height: '100%', left: 5, top: 20, right: 5, bottom: 25},\n    colors: [\"#00f\",\"#ff7f2a\",\"#008000\"],\n    series: {0: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 1: {lineWidth: 2, pointSize: 3, pointShape: \"circle\"}, 2: {lineWidth: 0.5, pointSize: 1, pointShape: \"circle\"}},\n    explorer: {\n    actions: ['dragToZoom', 'rightClickToReset'],\n    maxZoomIn: .15\n    },\n    hAxis: {\n    textPosition: 'in',\n    title: '',\n    viewWindowMode: 'explicit',\n    format: 'MM\/YYYY',\n    gridlines: {color: '#ebebf5'}\n    },\n    vAxis: {\n    textPosition: 'in',\n    title: '',\n    format: 'short',\n    viewWindowMode: 'explicit',\n    gridlines: {color: '#ebebf5'}\n    },\n    curveType: 'function',\n    width: largura,\n    height: 300,\n    backgroundColor: {stroke: 'blue', fill: '#f6f6fd', strokeWidth: 1}\n    };\n    var chart = new google.visualization.LineChart(document.getElementById('chart_div1'));\n    chart.draw(data, options);\n    });\n    }\n    \/\/ Carregar o script do Google Charts e iniciar o gr\u00e1fico espec\u00edfico\n    loadGoogleCharts(drawChart1);\n    <\/script><\/p>\n<div id=\"chart_div1\" style=\"min-height:300px;\"><\/div>\n<p>Os dados s\u00e3o apresentados com a ressalva de que a categoria do modelo, marca, mercado, entre outros fatores, podem influenciar nessas varia\u00e7\u00f5es.<\/p>\n<p><strong>Anos de fabrica\u00e7\u00e3o dispon\u00edveis deste modelo:<\/strong><\/p>\n<ul>\n<li><a href='\/fipet\/preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2002\/'><b>2002<\/b> &#8211; Die: 109.995<\/a><\/li>\n<li><a href='\/fipet\/preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2003\/'><b>2003<\/b> &#8211; Die: 113.495<\/a><\/li>\n<li><a href='\/fipet\/preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2004\/'><b>2004<\/b> &#8211; Die: 122.437<\/a><\/li>\n<li><a href='\/fipet\/preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2005\/'><b>2005<\/b> &#8211; Die: 128.999<\/a><\/li>\n<li><a href='\/fipet\/preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2006\/'><b>2006<\/b> &#8211; Die: 134.772<\/a><\/li>\n<li><a href='\/fipet\/preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2007\/'><b>2007<\/b> &#8211; Die: 138.142<\/a><\/li>\n<li><a href='\/fipet\/preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2008\/'><b>2008<\/b> &#8211; Die: 141.596<\/a><\/li>\n<li><a href='\/fipet\/preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2009\/'><b>2009<\/b> &#8211; Die: 145.137<\/a><\/li>\n<li><a href='\/fipet\/preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2010\/'><b>2010<\/b> &#8211; Die: 148.765<\/a><\/li>\n<li><a href='\/fipet\/preco-tabela-fipe-mercedes-benz-accelo-715c-2p-diesel-2011\/'><b>2011<\/b> &#8211; Die: 152.483<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>O pre\u00e7o fipe do modelo MERCEDES-BENZ Accelo 715C 2p Diesel 2007 a diesel \u00e9 de R$ 138.142, segundo dados da Tabela Fipe. No hist\u00f3rico de pre\u00e7os mais recentes, \u00e9 poss\u00edvel notar que este modelo obteve uma valoriza\u00e7\u00e3o acumulada de 99,60% entre maio de 2021 e maio de 2026: Em maio de 2021 o pre\u00e7o era de R$ 69.211 passando para R$ 138.142 em maio de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2713,2187,2650,2188],"tags":[2250,2230,2193],"class_list":["post-16134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accelo-715c-2p-diesel","category-fipe","category-mercedes-benz","category-trucks","tag-2250","tag-2230","tag-diesel"],"_links":{"self":[{"href":"https:\/\/motos-motor.com.br\/fipet\/wp-json\/wp\/v2\/posts\/16134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/motos-motor.com.br\/fipet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/motos-motor.com.br\/fipet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/motos-motor.com.br\/fipet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/motos-motor.com.br\/fipet\/wp-json\/wp\/v2\/comments?post=16134"}],"version-history":[{"count":0,"href":"https:\/\/motos-motor.com.br\/fipet\/wp-json\/wp\/v2\/posts\/16134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/motos-motor.com.br\/fipet\/wp-json\/wp\/v2\/media\/928"}],"wp:attachment":[{"href":"https:\/\/motos-motor.com.br\/fipet\/wp-json\/wp\/v2\/media?parent=16134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/motos-motor.com.br\/fipet\/wp-json\/wp\/v2\/categories?post=16134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/motos-motor.com.br\/fipet\/wp-json\/wp\/v2\/tags?post=16134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}